{"id":3429,"date":"2025-03-17T15:10:38","date_gmt":"2025-03-17T06:10:38","guid":{"rendered":"https:\/\/www.japanconsultingoffice.com\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/"},"modified":"2025-10-27T14:50:36","modified_gmt":"2025-10-27T05:50:36","slug":"die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters","status":"publish","type":"post","link":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/","title":{"rendered":"&#8222;Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dieses Mal m\u00f6chten wir mit einer kleinen bemalten Marmorplatte aus Asien beginnen, die aus den 1750er Jahren stammt und jetzt im Rijksmuseum in Amsterdam ausgestellt ist.<br>Auf dieser ist ein Paar in westlicher Kleidung zu sehen und in der Bildunterschrift hei\u00dft es erl\u00e4uternd \u00fcber die Europ\u00e4er dieser Zeit: \u201esie tragen Grass, essen von den B\u00e4umen und verachten ihre Herrscher\u201c. (Foto: <a href=\"http:\/\/goo.gl\/IaTGGy\">http:\/\/goo.gl\/IaTGGy<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Man sieht also, dass sowohl die Wahrnehmung interkultureller Unterschiede als auch darauf basierende Missverst\u00e4ndnisse schon vor \u00fcber 200 Jahren gang und g\u00e4be waren.<br>Auch heute beruhen interkulturelle Missverst\u00e4ndnisse meist auf unterschiedlichen kulturellen Werten. Diese Unterschiede wiederum zeigen sich am Arbeitsplatz oft in Verhaltensweisen, die aus der Sicht der jeweils anderen Kultur keinen Sinn zu machen scheinen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oft beruhen interkulturelle Missverst\u00e4ndnisse auf unterschiedlichen kulturellen Werten. Diese Unterschiede wiederum zeigen sich im Gesch\u00e4ftsleben h\u00e4ufig in Verhaltensweisen, die aus der Sicht der jeweils anderen Kultur keinen Sinn zu machen scheinen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die deutsche Gesch\u00e4ftskultur legt bekanntlich viel Wert auf Zuverl\u00e4ssigkeit und die Einhaltung von gegebenen Zusagen. In JCO Seminaren kommt aber sehr h\u00e4ufig folgende Beschwerde von japanischen Teilnehmern: \u201eIch habe mich fest darauf verlassen, dass mein deutscher Gesch\u00e4ftspartner etwas f\u00fcr mich erledigen wird, doch wenn ich um 17 Uhr telefonisch nachfrage, ist der\/diejenige schon nach Hause gegangen und die Arbeit noch nicht fertig. Haben die Leute denn kein Verantwortungsgef\u00fchl?\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fragt man das deutsche Gegen\u00fcber, k\u00f6nnen sie h\u00e4ufig die Klage \u00fcberhaupt nicht nachvollziehen und entgegnen: \u201eWenn ich etwas zusage, mache ich es auch!\u201c<br>Wir haben es also mit einander widersprechenden Eindr\u00fccken zu tun. Es lohnt sich, einen Schritt zur\u00fcck zu gehen und zuerst die kulturellen Werte zu betrachten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es gibt im Japanischen das bekannte Sprichwort \u201eTsuru no hitokoe\u201c, welches in etwa \u201eein Wort des Kranichs gen\u00fcgt\u201c bedeutet. In Japan steht dieser Vogel f\u00fcr Autorit\u00e4t und Weisheit.<br>In einer eher hierarchischen Gesellschaft wie Japan ist also dem Befehl des Kranichs, der hier f\u00fcr \u201eder Kunde oder Vorgesetzte\u201c steht, unbedingt Folge zu leisten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gehen wir zum Ausgangsszenario zur\u00fcck, zeigt sich die Wurzel des Missverst\u00e4ndnisses. In Japan ist bei einer Bitte des Kunden klar, dass dieser Auftrag \u00e4u\u00dferste Priorit\u00e4t hat, auch wenn er noch so beil\u00e4ufig ge\u00e4u\u00dfert wurde. Das hei\u00dft, er steht automatisch ganz oben auf der To-do-Liste des Dienstleisters\/Lieferanten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Deutschland hingegen, wo die Verantwortlichkeit f\u00fcr das eigene Aufgabenfeld sehr stark betont wird, hat \u00fcblicherweise jeder Mitarbeiter die T\u00e4tigkeiten f\u00fcr den Arbeitstag nach seiner Einsch\u00e4tzung priorisiert. Wenn der Kunde oder Chef in so einer Arbeitskultur um etwas bittet, rutscht diese sehr oft an das Ende der To-do-Liste und wird eventuell erst am n\u00e4chsten Tag abgearbeitet, nachdem alle vorher angefallenen Arbeiten erledigt sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Subjektiv gesehen haben beide Parteien nichts falsch gemacht und doch kommt es zu Problemen, die durchaus die Zusammenarbeit beeintr\u00e4chtigen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wir empfehlen in so einem Fall nicht die \u00dcbernahme der anderen kulturellen Werte, sondern lediglich eine verst\u00e4rkte Kommunikation, in der die Erwartungen des japanischen Gegen\u00fcber klar thematisiert werden.<br><\/strong><strong>Die simple Frage:<br>\u201eBy when do you need it? Will tomorrow afternoon be early enough.\u201c<br>beugt dem genannten Problem vor.<br><\/strong><strong>Wird der als Deadline zusagte Termin jedes Mal eingehalten, wird man auch in den Augen der japanischen Partner als zuverl\u00e4ssig gelten.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieses Mal m\u00f6chten wir mit einer kleinen bemalten Marmorplatte aus Asien beginnen, die aus den 1750er Jahren stammt und jetzt im Rijksmuseum in Amsterdam ausgestellt ist.Auf dieser ist ein Paar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6146,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-3429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-information-exchange-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters - Japan Consulting Office<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters - Japan Consulting Office\" \/>\n<meta property=\"og:description\" content=\"Dieses Mal m\u00f6chten wir mit einer kleinen bemalten Marmorplatte aus Asien beginnen, die aus den 1750er Jahren stammt und jetzt im Rijksmuseum in Amsterdam ausgestellt ist.Auf dieser ist ein Paar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/\" \/>\n<meta property=\"og:site_name\" content=\"Japan Consulting Office\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-17T06:10:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T05:50:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.japanconsultingoffice.com\/wp-content\/uploads\/2025\/03\/2018-04-11-12.25.22-4032x1344-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/#\\\/schema\\\/person\\\/ef60643f4f471c2aa8d02ee95b8aff68\"},\"headline\":\"&#8222;Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters\",\"datePublished\":\"2025-03-17T06:10:38+00:00\",\"dateModified\":\"2025-10-27T05:50:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/\"},\"wordCount\":574,\"publisher\":{\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/2018-04-11-12.25.22-4032x1344-1-scaled.jpg\",\"articleSection\":[\"Information Exchange\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/\",\"url\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/\",\"name\":\"\\\"Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters - Japan Consulting Office\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/2018-04-11-12.25.22-4032x1344-1-scaled.jpg\",\"datePublished\":\"2025-03-17T06:10:38+00:00\",\"dateModified\":\"2025-10-27T05:50:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/2018-04-11-12.25.22-4032x1344-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/2018-04-11-12.25.22-4032x1344-1-scaled.jpg\",\"width\":2560,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/#website\",\"url\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/\",\"name\":\"Japan Consulting Office\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/#organization\",\"name\":\"Japan Consulting Office\",\"url\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/cropped-LOGO_JCO-clear-background.png\",\"contentUrl\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/cropped-LOGO_JCO-clear-background.png\",\"width\":512,\"height\":512,\"caption\":\"Japan Consulting Office\"},\"image\":{\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/japan-consulting-office\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/#\\\/schema\\\/person\\\/ef60643f4f471c2aa8d02ee95b8aff68\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3765ebe7ff47d0239a58fee68726fa08473d2199eb253ae96876017def63951b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3765ebe7ff47d0239a58fee68726fa08473d2199eb253ae96876017def63951b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3765ebe7ff47d0239a58fee68726fa08473d2199eb253ae96876017def63951b?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.japanconsultingoffice.com\"],\"url\":\"https:\\\/\\\/www.japanconsultingoffice.com\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters - Japan Consulting Office","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/","og_locale":"de_DE","og_type":"article","og_title":"\"Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters - Japan Consulting Office","og_description":"Dieses Mal m\u00f6chten wir mit einer kleinen bemalten Marmorplatte aus Asien beginnen, die aus den 1750er Jahren stammt und jetzt im Rijksmuseum in Amsterdam ausgestellt ist.Auf dieser ist ein Paar [&hellip;]","og_url":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/","og_site_name":"Japan Consulting Office","article_published_time":"2025-03-17T06:10:38+00:00","article_modified_time":"2025-10-27T05:50:36+00:00","og_image":[{"width":2560,"height":853,"url":"https:\/\/www.japanconsultingoffice.com\/wp-content\/uploads\/2025\/03\/2018-04-11-12.25.22-4032x1344-1-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/#article","isPartOf":{"@id":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/"},"author":{"name":"admin","@id":"https:\/\/www.japanconsultingoffice.com\/#\/schema\/person\/ef60643f4f471c2aa8d02ee95b8aff68"},"headline":"&#8222;Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters","datePublished":"2025-03-17T06:10:38+00:00","dateModified":"2025-10-27T05:50:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/"},"wordCount":574,"publisher":{"@id":"https:\/\/www.japanconsultingoffice.com\/#organization"},"image":{"@id":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/#primaryimage"},"thumbnailUrl":"https:\/\/www.japanconsultingoffice.com\/wp-content\/uploads\/2025\/03\/2018-04-11-12.25.22-4032x1344-1-scaled.jpg","articleSection":["Information Exchange"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/","url":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/","name":"\"Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters - Japan Consulting Office","isPartOf":{"@id":"https:\/\/www.japanconsultingoffice.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/#primaryimage"},"image":{"@id":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/#primaryimage"},"thumbnailUrl":"https:\/\/www.japanconsultingoffice.com\/wp-content\/uploads\/2025\/03\/2018-04-11-12.25.22-4032x1344-1-scaled.jpg","datePublished":"2025-03-17T06:10:38+00:00","dateModified":"2025-10-27T05:50:36+00:00","breadcrumb":{"@id":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/#primaryimage","url":"https:\/\/www.japanconsultingoffice.com\/wp-content\/uploads\/2025\/03\/2018-04-11-12.25.22-4032x1344-1-scaled.jpg","contentUrl":"https:\/\/www.japanconsultingoffice.com\/wp-content\/uploads\/2025\/03\/2018-04-11-12.25.22-4032x1344-1-scaled.jpg","width":2560,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.japanconsultingoffice.com\/de\/die-stimme-des-kranichs-oder-zuverlaessigkeit-liegt-im-auge-des-betrachters\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.japanconsultingoffice.com\/de\/"},{"@type":"ListItem","position":2,"name":"&#8220;Die Stimme des Kranichs\u201c oder Zuverl\u00e4ssigkeit liegt im Auge des Betrachters"}]},{"@type":"WebSite","@id":"https:\/\/www.japanconsultingoffice.com\/#website","url":"https:\/\/www.japanconsultingoffice.com\/","name":"Japan Consulting Office","description":"","publisher":{"@id":"https:\/\/www.japanconsultingoffice.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.japanconsultingoffice.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.japanconsultingoffice.com\/#organization","name":"Japan Consulting Office","url":"https:\/\/www.japanconsultingoffice.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.japanconsultingoffice.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.japanconsultingoffice.com\/wp-content\/uploads\/2025\/04\/cropped-LOGO_JCO-clear-background.png","contentUrl":"https:\/\/www.japanconsultingoffice.com\/wp-content\/uploads\/2025\/04\/cropped-LOGO_JCO-clear-background.png","width":512,"height":512,"caption":"Japan Consulting Office"},"image":{"@id":"https:\/\/www.japanconsultingoffice.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/japan-consulting-office\/"]},{"@type":"Person","@id":"https:\/\/www.japanconsultingoffice.com\/#\/schema\/person\/ef60643f4f471c2aa8d02ee95b8aff68","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/3765ebe7ff47d0239a58fee68726fa08473d2199eb253ae96876017def63951b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3765ebe7ff47d0239a58fee68726fa08473d2199eb253ae96876017def63951b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3765ebe7ff47d0239a58fee68726fa08473d2199eb253ae96876017def63951b?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.japanconsultingoffice.com"],"url":"https:\/\/www.japanconsultingoffice.com\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.japanconsultingoffice.com\/de\/wp-json\/wp\/v2\/posts\/3429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.japanconsultingoffice.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.japanconsultingoffice.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.japanconsultingoffice.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.japanconsultingoffice.com\/de\/wp-json\/wp\/v2\/comments?post=3429"}],"version-history":[{"count":0,"href":"https:\/\/www.japanconsultingoffice.com\/de\/wp-json\/wp\/v2\/posts\/3429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.japanconsultingoffice.com\/de\/wp-json\/wp\/v2\/media\/6146"}],"wp:attachment":[{"href":"https:\/\/www.japanconsultingoffice.com\/de\/wp-json\/wp\/v2\/media?parent=3429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.japanconsultingoffice.com\/de\/wp-json\/wp\/v2\/categories?post=3429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.japanconsultingoffice.com\/de\/wp-json\/wp\/v2\/tags?post=3429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}